{"id":18495,"date":"2025-09-17T11:46:24","date_gmt":"2025-09-17T09:46:24","guid":{"rendered":"https:\/\/florjancic.si\/senza-categoria\/la-tecnologia-che-crea-qualita-2\/"},"modified":"2025-10-17T12:44:41","modified_gmt":"2025-10-17T10:44:41","slug":"la-tecnologia-che-crea-qualita-2","status":"publish","type":"post","link":"https:\/\/florjancic.si\/it\/notizie\/la-tecnologia-che-crea-qualita-2\/","title":{"rendered":"La tecnologia che crea qualit\u00e0"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"18495\" class=\"elementor elementor-18495 elementor-9745\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-61689bb7 e-con-full e-flex e-con e-parent\" data-id=\"61689bb7\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-10807ecb elementor-widget elementor-widget-text-editor\" data-id=\"10807ecb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"630\" data-end=\"888\">Nella tipografia Florjan\u010di\u010d crediamo che l\u2019eccellenza della stampa nasca dalla combinazione di conoscenza, esperienza e tecnologia d\u2019avanguardia. Il nostro parco macchine \u00e8 il risultato di anni di investimenti in qualit\u00e0, precisione e affidabilit\u00e0 \u2014 valori che ci accompagnano da oltre un secolo. <\/p><p data-start=\"890\" data-end=\"1220\">Con l\u2019ultima generazione di macchine da stampa e attrezzature moderne possiamo garantire un processo completo, dalla preparazione dei file fino alla rilegatura e al confezionamento finale. Le nostre capacit\u00e0 produttive ci permettono di realizzare in modo rapido ed efficiente anche i progetti pi\u00f9 complessi \u2014 che si tratti di monografie artistiche, cataloghi, libri o prodotti stampati su misura. <\/p><p data-start=\"2216\" data-end=\"2359\"> <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-779ff1f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"779ff1f\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"vamtam-has-theme-widget-styles elementor-element elementor-element-2f3b935a elementor-widget elementor-widget-heading\" data-id=\"2f3b935a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Precisione di stampa<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ea0f8b6 elementor-widget elementor-widget-text-editor\" data-id=\"2ea0f8b6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Il cuore della nostra produzione \u00e8 costituito da due macchine da stampa a 8 colori e una a 4 colori Heidelberg XL 106 \u2014 eccellenze della stampa offset che garantiscono straordinaria stabilit\u00e0 cromatica, ripetibilit\u00e0 e qualit\u00e0 di stampa superiore. Con queste macchine possiamo effettuare la stampa fronte-retro in un solo passaggio, ottenendo cos\u00ec una maggiore efficienza e un minore impatto ambientale. <\/p><p> <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54001731 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"54001731\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"vamtam-has-theme-widget-styles elementor-element elementor-element-5a23780e elementor-widget elementor-widget-heading\" data-id=\"5a23780e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Finitura che d\u00e0 forma al risultato finale<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f3e751c elementor-widget elementor-widget-text-editor\" data-id=\"5f3e751c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Per un aspetto perfetto dei prodotti stampati ci affidiamo alle nostre linee di finitura: verniciatura UV parziale (MGI) per effetti speciali, rilegatura integrale Petratto, stampa a caldo e a secco Kama, e macchine Kolbus per rilegature morbide e rigide. Disponiamo inoltre di macchinari per la produzione di scatole, il taglio del cartone, la plastificazione, la cucitura a punto metallico, nonch\u00e9 per la fustellatura e la cordonatura. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4150f236 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4150f236\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"vamtam-has-theme-widget-styles elementor-element elementor-element-5311fe59 elementor-widget elementor-widget-heading\" data-id=\"5311fe59\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Completezza del processo\n<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-157b94eb elementor-widget elementor-widget-text-editor\" data-id=\"157b94eb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Con oltre dieci piegatrici, due unit\u00e0 CTP e tre taglierine, ogni fase del processo avviene internamente \u2014 sotto il controllo dei nostri esperti. In questo modo possiamo mantenere un controllo totale sulla qualit\u00e0, la precisione e i tempi di produzione. <\/p><p>Ogni libro, catalogo o prodotto per l\u2019imballaggio che lascia la nostra tipografia porta con s\u00e9 la firma di una perfetta armonia tra tecnologia e sapere umano.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3364922 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3364922\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"vamtam-has-theme-widget-styles elementor-element elementor-element-dd78634 elementor-widget elementor-widget-heading\" data-id=\"dd78634\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Conclusione\n<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3420b2c elementor-widget elementor-widget-text-editor\" data-id=\"3420b2c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Siamo orgogliosi di mantenere un equilibrio tra tradizione e innovazione \u2014 con rispetto per l\u2019artigianalit\u00e0 e uno sguardo rivolto al futuro. Il nostro parco macchine non \u00e8 semplicemente un elenco di attrezzature, ma la base della nostra missione: creare stampe che superano ogni aspettativa. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Nella tipografia Florjan\u010di\u010d crediamo che l\u2019eccellenza della stampa nasca dalla combinazione di conoscenza, esperienza e tecnologia d\u2019avanguardia. Il nostro parco macchine \u00e8 il risultato di anni di investimenti in qualit\u00e0, precisione e affidabilit\u00e0 \u2014 valori che ci accompagnano da oltre un secolo. Con l\u2019ultima generazione di macchine da stampa e attrezzature moderne possiamo garantire un&#8230;<\/p>\n","protected":false},"author":1,"featured_media":18483,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[95],"tags":[],"class_list":["post-18495","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie"],"acf":[],"_links":{"self":[{"href":"https:\/\/florjancic.si\/it\/wp-json\/wp\/v2\/posts\/18495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/florjancic.si\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/florjancic.si\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/florjancic.si\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/florjancic.si\/it\/wp-json\/wp\/v2\/comments?post=18495"}],"version-history":[{"count":1,"href":"https:\/\/florjancic.si\/it\/wp-json\/wp\/v2\/posts\/18495\/revisions"}],"predecessor-version":[{"id":18496,"href":"https:\/\/florjancic.si\/it\/wp-json\/wp\/v2\/posts\/18495\/revisions\/18496"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/florjancic.si\/it\/wp-json\/wp\/v2\/media\/18483"}],"wp:attachment":[{"href":"https:\/\/florjancic.si\/it\/wp-json\/wp\/v2\/media?parent=18495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/florjancic.si\/it\/wp-json\/wp\/v2\/categories?post=18495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/florjancic.si\/it\/wp-json\/wp\/v2\/tags?post=18495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}